{"id":4186,"date":"2021-11-25T08:07:44","date_gmt":"2021-11-25T07:07:44","guid":{"rendered":"https:\/\/www.minemaster.eu\/product\/roof-master-2-3awk\/"},"modified":"2026-06-24T11:00:01","modified_gmt":"2026-06-24T09:00:01","slug":"roof-master-2-3awk","status":"publish","type":"products","link":"https:\/\/www.minemaster.eu\/es\/productos\/roof-master-2-3awk\/","title":{"rendered":"ROOF MASTER 2.310 AWK"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El equipo de atornillado autopropulsado Roof Master 2.310 AWK esdise\u00f1ado para trabajar en operaciones de escala media. La altura m\u00ednima de desplazamiento de este equipo es de 2,3 m.<\/p>\n","protected":false},"featured_media":2898,"parent":0,"menu_order":64,"template":"","class_list":["post-4186","products","type-products","status-publish","has-post-thumbnail","hentry","product_category-equipos-de-anclaje"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/products\/4186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":2,"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/products\/4186\/revisions"}],"predecessor-version":[{"id":4474,"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/products\/4186\/revisions\/4474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/media\/2898"}],"wp:attachment":[{"href":"https:\/\/www.minemaster.eu\/es\/wp-json\/wp\/v2\/media?parent=4186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}